{"id":1255,"date":"2019-09-24T16:21:40","date_gmt":"2019-09-24T19:21:40","guid":{"rendered":"https:\/\/www.manualdeideias.com\/estilo-de-vida\/saude\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/"},"modified":"2019-09-24T16:21:40","modified_gmt":"2019-09-24T19:21:40","slug":"bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga","status":"publish","type":"post","link":"https:\/\/www.conveniosocial.com.br\/blog\/saude\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/","title":{"rendered":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026"},"content":{"rendered":"\n<p><strong>Sabemos que existem alimentos que fazem milagres quando consumidos regularmente.<\/strong><\/p>\n<p><strong>S\u00e3o verdadeiros presentes do Criador para n\u00f3s.<\/strong><\/p>\n<p>Entre esses alimentos, h\u00e1 algumas frutas especiais que t\u00eam forte a\u00e7\u00e3o depurativa, ou seja, elas desintoxicam o nosso organismo, livrando nosso corpo de subst\u00e2ncias prejudiciais.<\/p>\n<p><strong>Uma dessas frutas \u00e9 o mam\u00e3o.<\/strong><\/p>\n<ul>\n<li>O mam\u00e3o \u00e9 rico em papa\u00edna, uma enzima muito \u00fatil nos casos de dificuldade de digerir alimentos.<\/li>\n<li>O mam\u00e3o maduro \u00e9 digestivo, diur\u00e9tico, emoliente, laxante e refrescante.<\/li>\n<li>Ele \u201climpa\u201d o aparelho digestivo.<\/li>\n<li>Auxilia, al\u00e9m disso, na manuten\u00e7\u00e3o do equil\u00edbrio \u00e1cido-alcalino do corpo.<\/li>\n<li>Ele \u00e9 rico em vitaminas e minerais, tendo cota generosa de vitamina A (pr\u00f3-vitamina), vitaminas do complexo B e rico teor de vitamina C.<\/li>\n<\/ul>\n<p>Segundo a medicina natural, o mam\u00e3o \u00e9 capaz de tratar mais de 40 doen\u00e7as.<\/p>\n<p>Uma forma excelente de utilizar o mam\u00e3o e aproveitar os seus benef\u00edcios \u00e9 consumindo a receita que voc\u00ea vai aprender agora.<\/p>\n<p>A vitamina de mam\u00e3o e aveia limpa todo o organismo.<\/p>\n<p>Ela vai desintoxicar seu aparelho digestivo, principalmente o intestino.<\/p>\n<p>Ela ajudar\u00e1 voc\u00ea a emagrecer, al\u00e9m de contribuir para normalizar as suas taxas de colesterol e triglic\u00e9rides.N\u00e3o s\u00f3 devido ao mam\u00e3o, mas tamb\u00e9m \u00e0 aveia.<\/p>\n<p>A fibra sol\u00favel chamada betaglucana \u00e9 respons\u00e1vel por boa parte das vantagens nutricionais proporcionadas pelo consumo da aveia.<\/p>\n<div class=\"ezAdsense adsense adsense-midtext\">\n<p>Essa fibra retarda o esvaziamento g\u00e1strico, o que tem como resultado uma sensa\u00e7\u00e3o de maior saciedade.<\/p>\n<p>Ao entrarem em contato com a \u00e1gua, as fibras se transformam em um gel que torna o bolo fecal maior e mais viscoso.<\/p>\n<p>Com isso, ocorre uma menor absor\u00e7\u00e3o de subst\u00e2ncias presentes neste bolo, como glicose e colesterol, devido a uma menor a\u00e7\u00e3o de enzimas digestivas.<\/p>\n<p>E, em rela\u00e7\u00e3o ao controle do colesterol, estudos sugerem que a a\u00e7\u00e3o da betaglucana na diminui\u00e7\u00e3o dessa gordura no sangue estaria ligada \u00e0 absor\u00e7\u00e3o de \u00e1cidos biliares.<\/p>\n<p>Tais \u00e1cidos s\u00e3o excretados pelas fezes, diminuindo a absor\u00e7\u00e3o de colesterol ou \u00e1cidos graxos de cadeia curta produzidos pela a\u00e7\u00e3o das fibras presentes no c\u00f3lon.<\/p>\n<p>Portanto, o consumo regular de aveia pode estar relacionado com a diminui\u00e7\u00e3o da forma\u00e7\u00e3o de placas de gorduras, que causam doen\u00e7as cardiovasculares<\/p>\n<p>A parte da aveia que possui maior quantidade de betaglucanas \u00e9 o farelo de aveia, seguido dos flocos e da farinha de aveia.<\/p>\n<p><strong>Veja como \u00e9 simples fazer:<\/strong><\/p>\n<p><strong>INGREDIENTES<\/strong><\/p>\n<ul>\n<li>Meia x\u00edcara de mam\u00e3o picado<\/li>\n<li>1 copo de iogurte natural desnatado ou de leite vegetal (como gergelim ou am\u00eandoas)<\/li>\n<li>2 colheres (sopa) de farelo aveia<\/li>\n<li>1 m\u00e3o cheia com salsinha (ramos e folhas)<\/li>\n<\/ul>\n<p><strong>MODO DE PREPARO<\/strong><\/p>\n<ul>\n<li>Bata todos os ingredientes no liquidificador.<\/li>\n<li>Tome imediatamente.<\/li>\n<li>Beba um copo desta bebida diariamente, em substitui\u00e7\u00e3o ao caf\u00e9 da manh\u00e3, durante 30 dias.<\/li>\n<li>Pode continuar tomando, se quiser, por mais tempo.<\/li>\n<\/ul>\n<p><em>Este \u00e9 um blog de not\u00edcias sobre tratamentos caseiros. Ele n\u00e3o substitui um especialista. Consulte sempre seu m\u00e9dico.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sabemos que existem alimentos que fazem milagres quando consumidos regularmente. S\u00e3o verdadeiros presentes do Criador para n\u00f3s. Entre esses alimentos, h\u00e1 algumas frutas especiais que t\u00eam forte a\u00e7\u00e3o depurativa, ou seja, elas desintoxicam o nosso organismo, livrando nosso corpo de subst\u00e2ncias prejudiciais. Uma dessas frutas \u00e9 o mam\u00e3o. O mam\u00e3o \u00e9 rico em papa\u00edna, uma [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1256,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"o","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[614],"tags":[],"class_list":["post-1255","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026 - Conv\u00eanio Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026\" \/>\n<meta property=\"og:description\" content=\"Sabemos que existem alimentos que fazem milagres quando consumidos regularmente. S\u00e3o verdadeiros presentes do Criador para n\u00f3s. Entre esses alimentos, h\u00e1 algumas frutas especiais que t\u00eam forte a\u00e7\u00e3o depurativa, ou seja, elas desintoxicam o nosso organismo, livrando nosso corpo de subst\u00e2ncias prejudiciais. Uma dessas frutas \u00e9 o mam\u00e3o. O mam\u00e3o \u00e9 rico em papa\u00edna, uma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/\" \/>\n<meta property=\"og:site_name\" content=\"Conv\u00eanio Social\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T19:21:40+00:00\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\"},\"headline\":\"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026\",\"datePublished\":\"2019-09-24T19:21:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/\"},\"wordCount\":506,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/\",\"name\":\"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026 - Conv\u00eanio Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-09-24T19:21:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nenhuma\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"name\":\"Conv\u00eanio Social\",\"description\":\"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\",\"name\":\"Conv\u00eanio Social\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"width\":400,\"height\":102,\"caption\":\"Conv\u00eanio Social\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"caption\":\"Reda\u00e7\u00e3o\"},\"description\":\"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026 - Conv\u00eanio Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/","og_locale":"pt_BR","og_type":"article","og_title":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026","og_description":"Sabemos que existem alimentos que fazem milagres quando consumidos regularmente. S\u00e3o verdadeiros presentes do Criador para n\u00f3s. Entre esses alimentos, h\u00e1 algumas frutas especiais que t\u00eam forte a\u00e7\u00e3o depurativa, ou seja, elas desintoxicam o nosso organismo, livrando nosso corpo de subst\u00e2ncias prejudiciais. Uma dessas frutas \u00e9 o mam\u00e3o. O mam\u00e3o \u00e9 rico em papa\u00edna, uma [&hellip;]","og_url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/","og_site_name":"Conv\u00eanio Social","article_published_time":"2019-09-24T19:21:40+00:00","author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#article","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb"},"headline":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026","datePublished":"2019-09-24T19:21:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/"},"wordCount":506,"commentCount":0,"publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#primaryimage"},"thumbnailUrl":"","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/","name":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026 - Conv\u00eanio Social","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#primaryimage"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-09-24T19:21:40+00:00","breadcrumb":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/bebida-especial-3-em-um-para-ajudar-a-perder-peso-e-barriga\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conveniosocial.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Nenhuma","item":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/"},{"@type":"ListItem","position":3,"name":"Bebida especial 3 em um : para ajudar a perder peso e barriga \u2026"}]},{"@type":"WebSite","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website","url":"https:\/\/www.conveniosocial.com.br\/blog\/","name":"Conv\u00eanio Social","description":"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular","publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conveniosocial.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization","name":"Conv\u00eanio Social","url":"https:\/\/www.conveniosocial.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","width":400,"height":102,"caption":"Conv\u00eanio Social"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","caption":"Reda\u00e7\u00e3o"},"description":"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares."}]}},"_links":{"self":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/1255","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1255"}],"version-history":[{"count":0,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/1255\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1255"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1255"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1255"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}