{"id":1666,"date":"2019-09-24T16:23:15","date_gmt":"2019-09-24T19:23:15","guid":{"rendered":"https:\/\/www.manualdeideias.com\/estilo-de-vida\/saude\/significados-das-cores-das-paredes\/"},"modified":"2019-09-24T16:23:15","modified_gmt":"2019-09-24T19:23:15","slug":"significados-das-cores-das-paredes","status":"publish","type":"post","link":"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/","title":{"rendered":"Significados das cores das paredes"},"content":{"rendered":"<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_83 counter-flat ez-toc-counter ez-toc-white ez-toc-container-direction\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">\u00cdndice do Conte\u00fado<\/p>\n<label for=\"ez-toc-cssicon-toggle-item-6a04427161e78\" class=\"ez-toc-cssicon-toggle-label\"><span class=\"ez-toc-cssicon\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/label><input type=\"checkbox\"  id=\"ez-toc-cssicon-toggle-item-6a04427161e78\" checked aria-label=\"Alternar\" \/><nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_amarelo\" >Pintar as paredes de amarelo<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_azul\" >Pintar as paredes de azul<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_branco\" >Pintar as paredes de branco<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredesde_castanho\" >Pintar as paredesde castanho<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_laranja\" >Pintar as paredes de laranja<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_preto\" >Pintar as paredes de preto<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_rosa\" >Pintar as paredes de rosa<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_roxo\" >Pintar as paredes de roxo<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_verde\" >Pintar as paredes de verde<\/a><\/li><li class='ez-toc-page-1'><a class=\"ez-toc-link ez-toc-heading-10\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/saude\/significados-das-cores-das-paredes\/#Pintar_as_paredes_de_vermelho\" >Pintar as paredes de vermelho<\/a><\/li><\/ul><\/nav><\/div>\n\n<p>Antes de escolher as tintas para pintar as paredes da sua casa, \u00e9 importante perceber como a escolha da cor afeta todo o ambiente em que vive. Lembre-se que a sua casa deve ser o seu ref\u00fagio: um lugar onde se sente confort\u00e1vel, seguro e feliz. Por isso, \u00e9 necess\u00e1rio fazer com que todo o interior lhe proporcione aquilo que mais deseja: seja paz, excita\u00e7\u00e3o, alegria, emo\u00e7\u00e3o, etc.<span id=\"more-1979\"><\/span><\/p>\n<div>\n<p>Hoje em dia \u00e9 bastante comum <strong>pintar<\/strong> apenas uma parede da divis\u00e3o com uma cor distinta, mais forte e contrastante. Esta \u00e9 uma op\u00e7\u00e3o moderna e interessante, que traz mais dinamismo e originalidade \u00e0 sua casa. De facto, ter uma casa com todas as paredes brancas pode ser mon\u00f3tono e ter pouca gra\u00e7a, mas \u00e9 preciso ter algum cuidado na hora de colorir o seu interior para n\u00e3o exagerar e n\u00e3o acabar por provocar efeitos contr\u00e1rios ao que deseja. Existem ainda outras op\u00e7\u00f5es no mercado para decorar as paredes, como \u00e9 o caso do vinil autocolante, onde pode colar alguns efeitos, quer tenha pintado (ou n\u00e3o) as suas paredes.<\/p>\n<p>Quer esteja a pensar pintar as paredesda sua casa ou a revesti-las com papel de parede, aescolha da cor das paredes deve-se centrar em diferentes fatores, nomeadamente o uso e a fun\u00e7\u00e3o da divis\u00e3o, o gosto pessoal e o efeito que se pretende. Assim, tanto poder\u00e1 querer alcan\u00e7ar uma sensa\u00e7\u00e3o relaxante ou por outro lado um efeito mais energ\u00e9tico \u2013 e a cor da parede ir\u00e1 contribuir imenso para isso.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_amarelo\"><\/span>Pintar as paredes de amarelo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>amarelo<\/strong> \u00e9 cor do sol e \u00e9 sin\u00f3nimo de calor, alegria e dinamismo. Espa\u00e7os <strong>pintados de amarelo<\/strong> tornam-se e geral mais otimistas, energ\u00e9ticos e felizes. Por\u00e9m cuidado: lembre-se que o perigo tamb\u00e9m \u00e9 assinalado pela cor amarela. Na verdade esta cor em demasia e em tons muito fortes e brilhantes poder\u00e1 provocar sensa\u00e7\u00f5es desagrad\u00e1veis e tornar-se algo agressiva. Assim, os tons mais claros e suaves de amarelo s\u00e3o em geral uma aposta mais confort\u00e1vel.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_azul\"><\/span>Pintar as paredes de azul<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>azul<\/strong> \u00e9 conhecido por ser uma cor serena, representando o c\u00e9u e o mar. Apesar de haver imensos tons de azul, em geral esta \u00e9 uma cor que provoca relaxamento e tamb\u00e9m seguran\u00e7a. Muitas vezes associada mais ao sexo masculino (sendo muito usada em quartos de meninos) na verdade esta \u00e9 uma cor com muito potencial que pode trazer suavidade e harmonia a todas as divis\u00f5es da sua casa \u2013 no entanto cuidado, pois muito <strong>azul nas paredes<\/strong> tamb\u00e9m poder\u00e1 fazer com que o espa\u00e7o pare\u00e7a mais frio ou triste.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_branco\"><\/span>Pintar as paredes de branco<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>branco<\/strong> \u00e9 luz, paz, serenidade, pureza e tamb\u00e9m espiritualidade. Ao pintar as<strong> paredes de branco<\/strong> consegue um efeito confort\u00e1vel, aconchegante, calmo e limpo. \u00c9 uma das melhores solu\u00e7\u00f5es para espa\u00e7os pequenos, por\u00e9m n\u00e3o deixa de ser uma aposta muito segura onde n\u00e3o se correm riscos: ao pintar tudo de branco poder\u00e1 simplesmente cair na monotonia e retirar alguma vida e emo\u00e7\u00e3o aos diferentes ambientes da sua casa.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredesde_castanho\"><\/span>Pintar as paredesde castanho<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>castanho<\/strong> \u00e9 a cor da terra e por isso est\u00e1 intimamente ligado \u00e0s natureza. Esta cor transmite-nos solidez, resist\u00eancia, maturidade e estabilidade; assim, ambientes <strong>pintados com tons de castanho<\/strong> tornam-se confort\u00e1veis, aconchegantes e simples. O castanho \u00e9 em geral uma cor calma e ideal para ambientes mais r\u00fasticos e tradicionais. Por\u00e9m, em demasia pode tornar o espa\u00e7o muito estagnado e por isso mon\u00f3tono.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_laranja\"><\/span>Pintar as paredes de laranja<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>laranja<\/strong> \u00e9 energia, vitalidade, divertimento e sucesso. Estando entre o amarelo e o vermelho, pintar uma <strong>parede de laranja<\/strong> d\u00e1 uma energia muito quente e animada, que consegue tornar o ambiente mais alegre e soci\u00e1vel, deixando as pessoas \u00e0 vontade. Esta \u00e9 uma cor que traz originalidade e espontaneidade \u00e0 sua casa, mas tenha em conta que em exagero pode provocar irritabilidade.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_preto\"><\/span>Pintar as paredes de preto<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>preto<\/strong> \u00e9 uma cor autorit\u00e1ria e austera, que por vezes tamb\u00e9m est\u00e1 associada a algo misterioso ou espiritual. Lembre-se que no ocidente esta \u00e9 a cor usada para o luto, por isso o preto pode-nos trazer esta carga emocional de tristeza e penit\u00eancia. Associada tamb\u00e9m \u00e0 solid\u00e3o, isolamento e prote\u00e7\u00e3o o preto \u00e9 aus\u00eancia de luz, gerando ambientes mais pequenos e at\u00e9 claustrof\u00f3bicos. Em exagero torna qualquer espa\u00e7o demasiado pesado e oprimido; por\u00e9m um pouco de <strong>preto nas suas paredes<\/strong> pode indicar um certo requinte, eleg\u00e2ncia, exclusividade e dignidade.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_rosa\"><\/span>Pintar as paredes de rosa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>rosa<\/strong> est\u00e1 quase sempre relacionado com o universo feminino, transmitindo muitas vezes sensibilidade, delicadeza, romantismo e beleza. Mas al\u00e9m disso, o rosa tamb\u00e9m tem a capacidade de acalmar ou mesmo melhor o humor, podendo por isso ser uma boa op\u00e7\u00e3o para diversos ambientes.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_roxo\"><\/span>Pintar as paredes de roxo<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>roxo<\/strong> simboliza prosperidade e luxo mas tamb\u00e9m espiritualidade, criatividade e imagina\u00e7\u00e3o. Sendo a cor da realeza, ela mostra poder e exclusividade. O <strong>roxo<\/strong> apresenta-se como uma cor forte que marca qualquer espa\u00e7o: desde o ousado roxo intenso ao mais tranquilizante e suave lil\u00e1s. No entanto, se optar mesmo por tons mais fortes, vibrantes ou escuros dever\u00e1 sempre ter algum cuidado extra para n\u00e3o exagerar.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_verde\"><\/span>Pintar as paredes de verde<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>verde<\/strong> \u00e9 uma cor refrescante e jovem, muitas vezes relacionada com o otimismo \u2013 por\u00e9m ela n\u00e3o \u00e9 demasiado excitante, \u00e9 mais serena e calma. Com capacidade de trazer a natureza para dentro de casa, a grande variedade de verdes permite diferentes op\u00e7\u00f5es interessantes para ambientes interiores. Al\u00e9m disso, a <strong>cor verde<\/strong> tamb\u00e9m \u00e9 associada a algo saud\u00e1vel e agrad\u00e1vel, o que \u00e9 sempre positivo.<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Pintar_as_paredes_de_vermelho\"><\/span>Pintar as paredes de vermelho<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>O <strong>vermelho<\/strong> \u00e9 paix\u00e3o e energia, mas tamb\u00e9m agressividade. No fundo, \u00e9 uma das cores mais intensas que poder\u00e1 usar em sua casa \u2013 e isto ter\u00e1 consequ\u00eancias reais, pois poder\u00e1 mesmo aumentar a frequ\u00eancia card\u00edaca de algumas pessoas. Casas com algumas <strong>paredes vermelhas<\/strong> s\u00e3o arrojadas, ousadas, originais e marcam bastante qualquer espa\u00e7o.<\/p>\n<p>Em geral \u2013 e como \u00e9 f\u00e1cil perceber \u2013 <strong>cores mais suaves<\/strong> d\u00e3o um efeito mais aconchegante e tranquilo ideal, para relaxar e dormir, enquanto que <strong>cores mais fortes<\/strong> provocam sensa\u00e7\u00f5es intensas e excitantes que s\u00e3o perfeitas para estimular e dar vida \u00e0 sua casa. No entanto, mesmo que pretenda um efeito mais estimulante, dever\u00e1 sempre usar as cores fortes ou brilhantes com alguma modera\u00e7\u00e3o.<\/p>\n<p>Por fim, tenha sempre em mente que a cor n\u00e3o \u00e9 apenas um elemento decorativo: \u00e9 mesmo um fator determinante para se sentir bem na sua pr\u00f3pria casa, pois leva sempre a uma rea\u00e7\u00e3o emocional. Por isso escolha com bom senso \u2013 sem nunca deixar de lado o seu gosto pessoal, claro.<\/p>\n<p><em>Artigo: dicascaseiras.com<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antes de escolher as tintas para pintar as paredes da sua casa, \u00e9 importante perceber como a escolha da cor afeta todo o ambiente em que vive. Lembre-se que a sua casa deve ser o seu ref\u00fagio: um lugar onde se sente confort\u00e1vel, seguro e feliz. Por isso, \u00e9 necess\u00e1rio fazer com que todo o [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"o","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[614],"tags":[],"class_list":["post-1666","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Significados das cores das paredes - Conv\u00eanio Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Significados das cores das paredes\" \/>\n<meta property=\"og:description\" content=\"Antes de escolher as tintas para pintar as paredes da sua casa, \u00e9 importante perceber como a escolha da cor afeta todo o ambiente em que vive. Lembre-se que a sua casa deve ser o seu ref\u00fagio: um lugar onde se sente confort\u00e1vel, seguro e feliz. Por isso, \u00e9 necess\u00e1rio fazer com que todo o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/\" \/>\n<meta property=\"og:site_name\" content=\"Conv\u00eanio Social\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T19:23:15+00:00\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\"},\"headline\":\"Significados das cores das paredes\",\"datePublished\":\"2019-09-24T19:23:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/\"},\"wordCount\":1148,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/\",\"name\":\"Significados das cores das paredes - Conv\u00eanio Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-09-24T19:23:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/significados-das-cores-das-paredes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nenhuma\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Significados das cores das paredes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"name\":\"Conv\u00eanio Social\",\"description\":\"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\",\"name\":\"Conv\u00eanio Social\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"width\":400,\"height\":102,\"caption\":\"Conv\u00eanio Social\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809\",\"caption\":\"Reda\u00e7\u00e3o\"},\"description\":\"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Significados das cores das paredes - Conv\u00eanio Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/","og_locale":"pt_BR","og_type":"article","og_title":"Significados das cores das paredes","og_description":"Antes de escolher as tintas para pintar as paredes da sua casa, \u00e9 importante perceber como a escolha da cor afeta todo o ambiente em que vive. Lembre-se que a sua casa deve ser o seu ref\u00fagio: um lugar onde se sente confort\u00e1vel, seguro e feliz. Por isso, \u00e9 necess\u00e1rio fazer com que todo o [&hellip;]","og_url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/","og_site_name":"Conv\u00eanio Social","article_published_time":"2019-09-24T19:23:15+00:00","author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"6 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#article","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb"},"headline":"Significados das cores das paredes","datePublished":"2019-09-24T19:23:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/"},"wordCount":1148,"commentCount":0,"publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#primaryimage"},"thumbnailUrl":"","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/","name":"Significados das cores das paredes - Conv\u00eanio Social","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#primaryimage"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-09-24T19:23:15+00:00","breadcrumb":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/significados-das-cores-das-paredes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conveniosocial.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Nenhuma","item":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/"},{"@type":"ListItem","position":3,"name":"Significados das cores das paredes"}]},{"@type":"WebSite","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website","url":"https:\/\/www.conveniosocial.com.br\/blog\/","name":"Conv\u00eanio Social","description":"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular","publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conveniosocial.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization","name":"Conv\u00eanio Social","url":"https:\/\/www.conveniosocial.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","width":400,"height":102,"caption":"Conv\u00eanio Social"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778654809","caption":"Reda\u00e7\u00e3o"},"description":"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares."}]}},"_links":{"self":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/1666","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1666"}],"version-history":[{"count":0,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/1666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}