{"id":969,"date":"2019-09-24T16:19:08","date_gmt":"2019-09-24T19:19:08","guid":{"rendered":"https:\/\/www.manualdeideias.com\/estilo-de-vida\/saude\/conheca-todos-os-poderes-naturais-da-curcuma\/"},"modified":"2019-09-24T16:19:08","modified_gmt":"2019-09-24T19:19:08","slug":"conheca-todos-os-poderes-naturais-da-curcuma","status":"publish","type":"post","link":"https:\/\/www.conveniosocial.com.br\/blog\/saude\/conheca-todos-os-poderes-naturais-da-curcuma\/","title":{"rendered":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma"},"content":{"rendered":"\n<p>Voc\u00ea sabe que a nossa luta pela divulga\u00e7\u00e3o das receitais naturais tem sido \u00e1rdua! N\u00f3s queremos que mais pessoas possam usufruir dos proveitos que a fant\u00e1stica natureza \u00e9 capaz de nos oferecer! <strong>Pois nela pode-se encontrar tratamentos bem acertados e formas de prevenir doen\u00e7as, naturalmente.<\/strong><\/p>\n<p>A dica deste artigo segue, mais uma vez, esse sentido. <strong>Vamos falar de uma especiaria bem comum nas nossas cozinhas e que tem imensos efeitos terap\u00eauticos e medicinais.<\/strong> Preste aten\u00e7\u00e3o, para o bem da sua sa\u00fade!<\/p>\n<p><strong>Propriedades da c\u00farcuma<\/strong><\/p>\n<p>Temos para voc\u00ea um medicamento bem natural, que vai acionar os mecanismos b\u00e1sicos que param com o crescimento de radicais livres, ou seja, os antioxidantes do organismo. A c\u00farcuma ou a\u00e7afr\u00e3o-da-terra, \u00e9 um tempero bem popular, bastante usado em diversas refei\u00e7\u00f5es. Contudo, ele \u00e9 um poderoso alimento com propriedades curativas, que resulta em proveitos para o corpo.<strong> \u00c9 incr\u00edvel, mas o a\u00e7afr\u00e3o cont\u00e9m 300 antioxidantes!<\/strong><\/p>\n<p>De forma a voc\u00ea tirar os melhores benef\u00edcios desta especiaria, vamos compartilhar com voc\u00ea uma receita natural bem simples. Para seu conhecimento, voc\u00ea apenas vai usar ingredientes comuns e baratos. Ver\u00e1 que vai gostar de experiment\u00e1-la!<\/p>\n<p><strong>Suco de c\u00farcuma<\/strong><\/p>\n<p><strong>Ingredientes:<\/strong><\/p>\n<ul>\n<li>C\u00farcuma (a\u00e7afr\u00e3o-da-terra) em p\u00f3: 1 colher de ch\u00e1;<\/li>\n<li>Laranja: 1 unidade;<\/li>\n<li>Gengibre: 1 peda\u00e7o com cerca de 5 cm;<\/li>\n<li>Pepino: 1 unidade;<\/li>\n<li>Lim\u00f5es: 2 unidades;<\/li>\n<li>Cenouras: 5 unidades.<\/li>\n<\/ul>\n<p><strong>Prepara\u00e7\u00e3o:<\/strong><\/p>\n<ul>\n<li>1. Em primeiro lugar, retire a casca das cenouras, da laranja, do gengibre e do lim\u00e3o.<\/li>\n<li>2. Depois, junte os ingredientes todos num liquidificador.<\/li>\n<li>3. Processe bem e a sua bebida estar\u00e1 pronta a tomar!<\/li>\n<li>4. Caso queira, pode deitar gelo para tornar a bebida mais fresca.<\/li>\n<\/ul>\n<p><strong>Benef\u00edcios do suco<\/strong><\/p>\n<p>Note que o suco de c\u00farcuma<strong> atenua o estado doloroso provocado pela artrite,<\/strong> pois \u00e9 composto por antioxidantes que tratam a inflama\u00e7\u00e3o e a rigidez do pulso. Os radicais livres acarretam diversas doen\u00e7as como aquela mais s\u00e9ria e complicada \u2013 o c\u00e2ncer. Voc\u00ea pode contar com este suco para evitar ter variados tipos de c\u00e2ncer: mam\u00e1rio, dos ov\u00e1rios, prost\u00e1tico e do intestino grosso.<\/p>\n<p>O suco deste tempero consegue<strong> tamb\u00e9m reduzir azia, gases e gastrite.<\/strong> Al\u00e9m disso, ainda <strong>controla o colesterol, previne doen\u00e7as de foro cardiovascular e trata dos vasos sangu\u00edneos e do cora\u00e7\u00e3o.<\/strong><\/p>\n<p>N\u00e3o perca todos os proveitos da c\u00farcuma e trate de us\u00e1-la mais vezes nas suas refei\u00e7\u00f5es. Para facilitar, tome o suco da receita e ver\u00e1 que a sua sa\u00fade sair\u00e1 refor\u00e7ada, de forma bem natural!<\/p>\n<p><em>As dicas deste artigo na\u0303o substituem a consulta ao me\u0301dico. Lembre-se que cada organismo e\u0301 u\u0301nico e pode reagir de forma diferente ao mencionado. E para obter os resultados mencionados tambe\u0301m e\u0301 preciso aliar a uma vida e alimentac\u0327a\u0303o sauda\u0301vel e equilibrada.<\/em><\/p>\n<p><em>[in:.dicasonline.tv]<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe que a nossa luta pela divulga\u00e7\u00e3o das receitais naturais tem sido \u00e1rdua! N\u00f3s queremos que mais pessoas possam usufruir dos proveitos que a fant\u00e1stica natureza \u00e9 capaz de nos oferecer! Pois nela pode-se encontrar tratamentos bem acertados e formas de prevenir doen\u00e7as, naturalmente. A dica deste artigo segue, mais uma vez, esse sentido. [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"o","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[614],"tags":[],"class_list":["post-969","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-saude"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v21.3 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Conhe\u00e7a todos os poderes naturais da c\u00farcuma - Conv\u00eanio Social<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Conhe\u00e7a todos os poderes naturais da c\u00farcuma\" \/>\n<meta property=\"og:description\" content=\"Voc\u00ea sabe que a nossa luta pela divulga\u00e7\u00e3o das receitais naturais tem sido \u00e1rdua! N\u00f3s queremos que mais pessoas possam usufruir dos proveitos que a fant\u00e1stica natureza \u00e9 capaz de nos oferecer! Pois nela pode-se encontrar tratamentos bem acertados e formas de prevenir doen\u00e7as, naturalmente. A dica deste artigo segue, mais uma vez, esse sentido. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/\" \/>\n<meta property=\"og:site_name\" content=\"Conv\u00eanio Social\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-24T19:19:08+00:00\" \/>\n<meta name=\"author\" content=\"Reda\u00e7\u00e3o\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Reda\u00e7\u00e3o\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/\"},\"author\":{\"name\":\"Reda\u00e7\u00e3o\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\"},\"headline\":\"Conhe\u00e7a todos os poderes naturais da c\u00farcuma\",\"datePublished\":\"2019-09-24T19:19:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/\"},\"wordCount\":487,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"articleSection\":[\"Sa\u00fade\"],\"inLanguage\":\"pt-BR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/\",\"name\":\"Conhe\u00e7a todos os poderes naturais da c\u00farcuma - Conv\u00eanio Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#primaryimage\"},\"thumbnailUrl\":\"\",\"datePublished\":\"2019-09-24T19:19:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#primaryimage\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/conheca-todos-os-poderes-naturais-da-curcuma\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nenhuma\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/nehuma\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Conhe\u00e7a todos os poderes naturais da c\u00farcuma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"name\":\"Conv\u00eanio Social\",\"description\":\"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#organization\",\"name\":\"Conv\u00eanio Social\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/uploads\\\/2021\\\/11\\\/novo_logo-convenio-socia-digital.png\",\"width\":400,\"height\":102,\"caption\":\"Conv\u00eanio Social\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/#\\\/schema\\\/person\\\/95c30bfdd058f90f62325275583f6bdb\",\"name\":\"Reda\u00e7\u00e3o\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/blog\\\/wp-content\\\/litespeed\\\/avatar\\\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846\",\"caption\":\"Reda\u00e7\u00e3o\"},\"description\":\"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma - Conv\u00eanio Social","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/","og_locale":"pt_BR","og_type":"article","og_title":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma","og_description":"Voc\u00ea sabe que a nossa luta pela divulga\u00e7\u00e3o das receitais naturais tem sido \u00e1rdua! N\u00f3s queremos que mais pessoas possam usufruir dos proveitos que a fant\u00e1stica natureza \u00e9 capaz de nos oferecer! Pois nela pode-se encontrar tratamentos bem acertados e formas de prevenir doen\u00e7as, naturalmente. A dica deste artigo segue, mais uma vez, esse sentido. [&hellip;]","og_url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/","og_site_name":"Conv\u00eanio Social","article_published_time":"2019-09-24T19:19:08+00:00","author":"Reda\u00e7\u00e3o","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Reda\u00e7\u00e3o","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#article","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/"},"author":{"name":"Reda\u00e7\u00e3o","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb"},"headline":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma","datePublished":"2019-09-24T19:19:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/"},"wordCount":487,"commentCount":0,"publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#primaryimage"},"thumbnailUrl":"","articleSection":["Sa\u00fade"],"inLanguage":"pt-BR"},{"@type":"WebPage","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/","name":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma - Conv\u00eanio Social","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#primaryimage"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#primaryimage"},"thumbnailUrl":"","datePublished":"2019-09-24T19:19:08+00:00","breadcrumb":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#primaryimage","url":"","contentUrl":""},{"@type":"BreadcrumbList","@id":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/conheca-todos-os-poderes-naturais-da-curcuma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.conveniosocial.com.br\/blog\/"},{"@type":"ListItem","position":2,"name":"Nenhuma","item":"https:\/\/www.conveniosocial.com.br\/blog\/nehuma\/"},{"@type":"ListItem","position":3,"name":"Conhe\u00e7a todos os poderes naturais da c\u00farcuma"}]},{"@type":"WebSite","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#website","url":"https:\/\/www.conveniosocial.com.br\/blog\/","name":"Conv\u00eanio Social","description":"Informa\u00e7\u00f5es de Sa\u00fade e Bem-estar, Consultas e Exames Popular","publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conveniosocial.com.br\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#organization","name":"Conv\u00eanio Social","url":"https:\/\/www.conveniosocial.com.br\/blog\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/uploads\/2021\/11\/novo_logo-convenio-socia-digital.png","width":400,"height":102,"caption":"Conv\u00eanio Social"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.conveniosocial.com.br\/blog\/#\/schema\/person\/95c30bfdd058f90f62325275583f6bdb","name":"Reda\u00e7\u00e3o","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","url":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","contentUrl":"https:\/\/www.conveniosocial.com.br\/blog\/wp-content\/litespeed\/avatar\/4e54f19e6593de883bfb434e7ed885ea.jpg?ver=1778049846","caption":"Reda\u00e7\u00e3o"},"description":"Presente nos 26 estados do Pa\u00eds e no Distrito Federal, Conv\u00eanio Social vem simplificando a experi\u00eancia dos usu\u00e1rios, que por meio do nosso portal, encontram, em um s\u00f3 local, tudo o que se refere aos servi\u00e7os de sa\u00fade a pre\u00e7os populares."}]}},"_links":{"self":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/969","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/comments?post=969"}],"version-history":[{"count":0,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/posts\/969\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/media?parent=969"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/categories?post=969"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/blog\/wp-json\/wp\/v2\/tags?post=969"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}