{"id":149403,"date":"2022-02-09T20:01:23","date_gmt":"2022-02-09T23:01:23","guid":{"rendered":"https:\/\/www.conveniosocial.com.br\/dentistas\/local\/santana-do-sao-francisco-se\/"},"modified":"2022-02-09T20:01:23","modified_gmt":"2022-02-09T23:01:23","slug":"santana-do-sao-francisco-se","status":"publish","type":"local","link":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/","title":{"rendered":"Santana do S\u00e3o Francisco &#8211; SE"},"content":{"rendered":"<p><strong>Conhe\u00e7a um pouco sobre o Munic\u00edpio de Santana do S\u00e3o Francisco &#8211; SE.<\/strong><\/p>\n<p>Santana do S\u00e3o Francisco \u00e9 uma cidade de Estado do Sergipe. Os habitantes se chamam santanenses.<\/p>\n<p>A densidade demogr\u00e1fica \u00e9 de 170,5 habitantes por km\u00b2 no territ\u00f3rio do munic\u00edpio. O munic\u00edpio se estende por 45,6 km\u00b2 e contava com 7 780 habitantes no \u00faltimo censo.Vizinho dos munic\u00edpios de Ne\u00f3polis, Penedo e Pacatuba,Santana do S\u00e3o Francisco se situa a 5 km a Sul-Oeste de Penedo a maior cidade nos arredores.<\/p>\n<p><strong>Como Chegar em Santana do S\u00e3o Francisco &#8211; Sergipe?<\/strong><\/p>\n<p>Situado a 85 metros de altitude, de Santana do S\u00e3o Francisco tem as seguintes coordenadas geogr\u00e1ficas: Latitude: 10\u00b0 18&#8242; 54&#8221; Sul, Longitude: 36\u00b0 36&#8242; 48&#8221; Oeste<\/p>\n<p>Procure por  <strong>Dentistas<\/strong> em cidade pr\u00f3xima como Pinh\u00e3o, Macambira, Frei Paulo.<\/p>\n","protected":false},"featured_media":0,"template":"","uf":[17],"class_list":["post-149403","local","type-local","status-publish","hentry","uf-se"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v25.7.1 (Yoast SEO v27.6) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dentistas em Santana do S\u00e3o Francisco - SE - Conv\u00eanio Social<\/title>\n<meta name=\"description\" content=\"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santana do S\u00e3o Francisco - SE\" \/>\n<meta property=\"og:description\" content=\"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/\" \/>\n<meta property=\"og:site_name\" content=\"Dentistas\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2023\/02\/banner-consultas-desktop-e1677588005571.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"499\" \/>\n\t<meta property=\"og:image:height\" content=\"499\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/santana-do-sao-francisco-se\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/santana-do-sao-francisco-se\\\/\",\"name\":\"Dentistas em Santana do S\u00e3o Francisco - SE - Conv\u00eanio Social\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#website\"},\"datePublished\":\"2022-02-09T23:01:23+00:00\",\"description\":\"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/santana-do-sao-francisco-se\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/santana-do-sao-francisco-se\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/santana-do-sao-francisco-se\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Dentistas\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Locais\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/local\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"SE\",\"item\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/se\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Santana do S\u00e3o Francisco &#8211; SE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#website\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/\",\"name\":\"Dentistas - Conv\u00eanio Social\",\"description\":\"Encontre Cl\u00ednicas Odontol\u00f3gicas - Dentistas Especializados\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#organization\"},\"alternateName\":\"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#organization\",\"name\":\"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/novo_logo-convenio-socia-digital1.png\",\"contentUrl\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/wp-content\\\/uploads\\\/sites\\\/5\\\/2023\\\/02\\\/novo_logo-convenio-socia-digital1.png\",\"width\":400,\"height\":102,\"caption\":\"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social\"},\"image\":{\"@id\":\"https:\\\/\\\/www.conveniosocial.com.br\\\/dentistas\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dentistas em Santana do S\u00e3o Francisco - SE - Conv\u00eanio Social","description":"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/","og_locale":"pt_BR","og_type":"article","og_title":"Santana do S\u00e3o Francisco - SE","og_description":"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE","og_url":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/","og_site_name":"Dentistas","og_image":[{"width":499,"height":499,"url":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2023\/02\/banner-consultas-desktop-e1677588005571.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/","url":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/","name":"Dentistas em Santana do S\u00e3o Francisco - SE - Conv\u00eanio Social","isPartOf":{"@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#website"},"datePublished":"2022-02-09T23:01:23+00:00","description":"Dentistas em Santana do S\u00e3o Francisco - SE. Encontre e agende uma consulta popular com Cl\u00ednicas Odontol\u00f3gicas - Dentistas pre\u00e7o popular em Santana do S\u00e3o Francisco - SE","breadcrumb":{"@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/santana-do-sao-francisco-se\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Dentistas","item":"https:\/\/www.conveniosocial.com.br\/dentistas\/"},{"@type":"ListItem","position":2,"name":"Locais","item":"https:\/\/www.conveniosocial.com.br\/dentistas\/local\/"},{"@type":"ListItem","position":3,"name":"SE","item":"https:\/\/www.conveniosocial.com.br\/dentistas\/se\/"},{"@type":"ListItem","position":4,"name":"Santana do S\u00e3o Francisco &#8211; SE"}]},{"@type":"WebSite","@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#website","url":"https:\/\/www.conveniosocial.com.br\/dentistas\/","name":"Dentistas - Conv\u00eanio Social","description":"Encontre Cl\u00ednicas Odontol\u00f3gicas - Dentistas Especializados","publisher":{"@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#organization"},"alternateName":"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.conveniosocial.com.br\/dentistas\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#organization","name":"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social","url":"https:\/\/www.conveniosocial.com.br\/dentistas\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#\/schema\/logo\/image\/","url":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2023\/02\/novo_logo-convenio-socia-digital1.png","contentUrl":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-content\/uploads\/sites\/5\/2023\/02\/novo_logo-convenio-socia-digital1.png","width":400,"height":102,"caption":"Cl\u00ednicas Odontol\u00f3gicas - Dentistas - Conv\u00eanio Social"},"image":{"@id":"https:\/\/www.conveniosocial.com.br\/dentistas\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-json\/wp\/v2\/local\/149403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-json\/wp\/v2\/local"}],"about":[{"href":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-json\/wp\/v2\/types\/local"}],"wp:attachment":[{"href":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-json\/wp\/v2\/media?parent=149403"}],"wp:term":[{"taxonomy":"uf","embeddable":true,"href":"https:\/\/www.conveniosocial.com.br\/dentistas\/wp-json\/wp\/v2\/uf?post=149403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}